
{"id":9795,"date":"2026-06-27T18:15:27","date_gmt":"2026-06-27T21:15:27","guid":{"rendered":"https:\/\/moderniza.me\/juventude\/?post_type=product&#038;p=9795"},"modified":"2026-07-13T09:05:30","modified_gmt":"2026-07-13T12:05:30","slug":"camisa-oficial-2026-3-listrada-masculina","status":"publish","type":"product","link":"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/","title":{"rendered":"CAMISA OFICIAL 2026\/3 LISTRADA MASCULINA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Na d\u00e9cada de 1920, o Juventude consolidou sua identidade vencedora. Com a chegada dos primeiros jogadores uruguaios e uma sequ\u00eancia hist\u00f3rica de conquistas, o clube fortaleceu sua reputa\u00e7\u00e3o e construiu o cap\u00edtulo inaugural de sua trajet\u00f3ria de vit\u00f3rias. <\/p>\n<p>A d\u00e9cada de 1920 foi o chute inicial que colocou o Esporte Clube Juventude no alto da prateleira dos grandes clubes do Rio Grande do Sul.<\/p>\n<p>Esta camisa revisita esse per\u00edodo, unindo a eleg\u00e2ncia do futebol dos anos 20 \u00e0 tecnologia do vestu\u00e1rio esportivo contempor\u00e2neo.<\/p>\n<p>O tecido jacquard transforma a pr\u00f3pria superf\u00edcie da pe\u00e7a em narrativa, incorporando refer\u00eancias hist\u00f3ricas em relevos discretos que revelam a riqueza dessa d\u00e9cada. A tradicional faixa horizontal resgata o visual dos uniformes da \u00e9poca, enquanto a gola canelada reinterpretada refor\u00e7a o car\u00e1ter cl\u00e1ssico e atemporal da composi\u00e7\u00e3o.<\/p>\n<p>Um dos principais elementos da pe\u00e7a est\u00e1 na abertura da gola. Inspirada nos uniformes utilizados no in\u00edcio do s\u00e9culo passado, a amarra\u00e7\u00e3o com cord\u00e3o remete aos modelos da \u00e9poca, quando as camisas eram fechadas por barbantes e cadar\u00e7os. Um detalhe hist\u00f3rico reinterpretado com acabamento contempor\u00e2neo, conectando diretamente o uniforme atual \u00e0s suas origens.<\/p>\n<p>Na parte interna, a frase \u201cHist\u00f3ria vive em n\u00f3s\u201d traduz o conceito da cole\u00e7\u00e3o: a certeza de que cada gera\u00e7\u00e3o carrega consigo o legado constru\u00eddo por quem veio antes.<\/p>\n<p>O detalhe dourado com o n\u00famero 1913 presta  homenagem ao ano de funda\u00e7\u00e3o do clube. Mais do que uma data, representa a origem de uma hist\u00f3ria que atravessa gera\u00e7\u00f5es e segue inspirando novos cap\u00edtulos.<\/p>\n<p>Uma camisa que conecta passado e futuro.<br \/>\nQue transforma mem\u00f3ria em identidade.<\/p>\n<p>E que celebra a hist\u00f3ria de um clube que continua vivendo em cada juventudista.<\/p>\n<p>#Juventude2026 #19Treze<\/p>\n","protected":false},"featured_media":9935,"template":"","meta":{"spay_email":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CAMISA OFICIAL 2026\/3 LISTRADA MASCULINA - Loja do Juventude<\/title>\n<meta name=\"description\" content=\"Diante da maior trag\u00e9dia ambiental no nosso Estado, nossos n\u00fameros v\u00e3o carregar as cores do Rio Grande do Sul, chamando a aten\u00e7\u00e3o para que as colabora\u00e7\u00f5es continuem e as fam\u00edlias atingidas sigam recebendo o suporte para que retomem suas vidas o mais r\u00e1pido poss\u00edvel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMISA OFICIAL 2026\/3 LISTRADA MASCULINA - Loja do Juventude\" \/>\n<meta property=\"og:description\" content=\"Diante da maior trag\u00e9dia ambiental no nosso Estado, nossos n\u00fameros v\u00e3o carregar as cores do Rio Grande do Sul, chamando a aten\u00e7\u00e3o para que as colabora\u00e7\u00f5es continuem e as fam\u00edlias atingidas sigam recebendo o suporte para que retomem suas vidas o mais r\u00e1pido poss\u00edvel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja do Juventude\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T12:05:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moderniza.me\/juventude\/wp-content\/uploads\/sites\/45\/2026\/06\/IMG_5676-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1335\" \/>\n\t<meta property=\"og:image:height\" content=\"1599\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/moderniza.me\/juventude\/#website\",\"url\":\"https:\/\/moderniza.me\/juventude\/\",\"name\":\"Loja do Juventude\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/moderniza.me\/juventude\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/moderniza.me\/juventude\/wp-content\/uploads\/sites\/45\/2026\/06\/IMG_5676-1.jpg\",\"width\":1335,\"height\":1599},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/#webpage\",\"url\":\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/\",\"name\":\"CAMISA OFICIAL 2026\/3 LISTRADA MASCULINA - Loja do Juventude\",\"isPartOf\":{\"@id\":\"https:\/\/moderniza.me\/juventude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/#primaryimage\"},\"datePublished\":\"2026-06-27T21:15:27+00:00\",\"dateModified\":\"2026-07-13T12:05:30+00:00\",\"description\":\"Diante da maior trag\\u00e9dia ambiental no nosso Estado, nossos n\\u00fameros v\\u00e3o carregar as cores do Rio Grande do Sul, chamando a aten\\u00e7\\u00e3o para que as colabora\\u00e7\\u00f5es continuem e as fam\\u00edlias atingidas sigam recebendo o suporte para que retomem suas vidas o mais r\\u00e1pido poss\\u00edvel.\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/moderniza.me\/juventude\/product\/camisa-oficial-2026-3-listrada-masculina\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/moderniza.me\/juventude\/wp-json\/wp\/v2\/product\/9795"}],"collection":[{"href":"https:\/\/moderniza.me\/juventude\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/moderniza.me\/juventude\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moderniza.me\/juventude\/wp-json\/wp\/v2\/media\/9935"}],"wp:attachment":[{"href":"https:\/\/moderniza.me\/juventude\/wp-json\/wp\/v2\/media?parent=9795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}